{"id":72076,"date":"2025-08-28T14:43:26","date_gmt":"2025-08-28T14:43:26","guid":{"rendered":"https:\/\/vinoeoli.it\/deluxe-2-5\/"},"modified":"2025-11-21T15:47:51","modified_gmt":"2025-11-21T15:47:51","slug":"deluxe-2-5","status":"publish","type":"post","link":"https:\/\/vinoeoli.it\/en\/deluxe-2-5\/","title":{"rendered":"DELUXE 2.5"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_flex_section\">\n<div class=\"et_pb_row_0 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_0 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>This is a welcoming solution suitable for short or medium stays. Ideal for a couple or families.<br \/>Covering 50 square meters, with both external and internal views, it features terrazzo or parquet flooring. The living area includes a fully equipped kitchen, a dining table, and a sitting area with a sofa bed and TV.<br \/>The sleeping area is separate, featuring a king-size bed and a TV. The bathroom, boasting a large marble shower or a bathtub, comes with a complete set of amenities.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_1 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_1 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24\">\n<div class=\"et_pb_gallery_0 et_pb_gallery et_pb_bg_layout_light et_pb_gallery_grid et_pb_module\" data-auto-rotate=\"off\" data-auto-rotate-speed=\"\"><div class=\"et_pb_gallery_items et_post_gallery clearfix et_grid_module\" data-per_page=\"15\"><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_0\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-amazing-living-room.jpg\" title=\"apartment-with-amazing-living-room\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-amazing-living-room-400x284.jpg\" alt=\"\" class=\"wp-image-72065\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-amazing-living-room.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-amazing-living-room-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_1\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bedroom-near-Vatican.jpg\" title=\"apartment-with-bedroom-near-Vatican\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bedroom-near-Vatican-400x284.jpg\" alt=\"\" class=\"wp-image-72067\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bedroom-near-Vatican.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bedroom-near-Vatican-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_2\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-kitchen-in-Rome-1.jpg\" title=\"apartment-with-kitchen-in-Rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-kitchen-in-Rome-1-400x284.jpg\" alt=\"\" class=\"wp-image-72068\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-kitchen-in-Rome-1.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-kitchen-in-Rome-1-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_3\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-covid-free-in-Prati-a-Roma.jpg\" title=\"Covid-Free Apartment in Prati, Rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-covid-free-in-Prati-a-Roma-400x284.jpg\" alt=\"\" class=\"wp-image-72070\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-covid-free-in-Prati-a-Roma.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-covid-free-in-Prati-a-Roma-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_4\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-lungo-periodo-in-Prati-a-Roma.jpg\" title=\"long stay apartments-in-Prati-Roma\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-lungo-periodo-in-Prati-a-Roma-400x284.jpg\" alt=\"\" class=\"wp-image-72061\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-lungo-periodo-in-Prati-a-Roma.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-lungo-periodo-in-Prati-a-Roma-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_5\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-bathroom-in-rome.jpg\" title=\"luxury-bathroom-in-rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-bathroom-in-rome-400x284.jpg\" alt=\"\" class=\"wp-image-72073\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-bathroom-in-rome.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-bathroom-in-rome-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_6\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-sofabed-in-rome.jpg\" title=\"apartment-with-sofabed-in-rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-sofabed-in-rome-400x284.jpg\" alt=\"\" class=\"wp-image-72069\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-sofabed-in-rome.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-sofabed-in-rome-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_7\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bathroom-in-rome.jpg\" title=\"apartment-with-bathroom-in-rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bathroom-in-rome-400x284.jpg\" alt=\"\" class=\"wp-image-72066\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bathroom-in-rome.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-with-bathroom-in-rome-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_8\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/vintage-furniture-bedroom.jpg\" title=\"vintage-furniture-bedroom\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/vintage-furniture-bedroom-400x284.jpg\" alt=\"\" class=\"wp-image-72074\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/vintage-furniture-bedroom.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/vintage-furniture-bedroom-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_9\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/amazing-bedroom-in-rome.jpg\" title=\"amazing-bedroom-in-rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/amazing-bedroom-in-rome-400x284.jpg\" alt=\"\" class=\"wp-image-72063\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/amazing-bedroom-in-rome.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/amazing-bedroom-in-rome-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_10\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-smart-working-a-Roma-Prati.jpg\" title=\"appartamento-per-smart-working-a-Roma-Prati\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-smart-working-a-Roma-Prati-400x284.jpg\" alt=\"\" class=\"wp-image-72071\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-smart-working-a-Roma-Prati.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/appartamento-per-smart-working-a-Roma-Prati-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_11\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-for-family-in-rome.jpg\" title=\"apartment-for-family-in-rome\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-for-family-in-rome-400x284.jpg\" alt=\"\" class=\"wp-image-72064\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-for-family-in-rome.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/apartment-for-family-in-rome-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><div class=\"et_pb_gallery_item et_pb_grid_item et_pb_gallery_item_0_12\"><div class=\"et_pb_gallery_image landscape\" data-per_page=\"15\"><a href=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-apartment-in-Rome-covid-free.jpg\" title=\"luxury-apartment-in-Rome-covid-free\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"284\" src=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-apartment-in-Rome-covid-free-400x284.jpg\" alt=\"\" class=\"wp-image-72072\" srcset=\"https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-apartment-in-Rome-covid-free.jpg 479w, https:\/\/vinoeoli.it\/wp-content\/uploads\/2025\/08\/luxury-apartment-in-Rome-covid-free-400x284.jpg 480w\" sizes=\"(max-width:479px) 479px, 100vw\" \/><span class=\"et_overlay\" data-icon=\"\" data-icon-tablet=\"\" data-icon-phone=\"\"><\/span><\/a><\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_flex_row\">\n<div class=\"et_pb_column_2 et_pb_column et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24\">\n<div class=\"et_pb_code_0 et_pb_code et_pb_text_align_center et_pb_module\"><div class=\"et_pb_code_inner\"><div id=\"apartmentIframe1858823\">\n<script type=\"text\/javascript\" src=\"https:\/\/login.smoobu.com\/js\/Settings\/BookingToolIframe.js\"><\/script>\n<script>BookingToolIframe.initialize({\"url\": \"https:\/\/login.smoobu.com\/en\/booking-tool\/iframe\/48292\/1858823\", \"baseUrl\": \"https:\/\/login.smoobu.com\", \"target\": \"#apartmentIframe1858823\"})<\/script>\n<\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et-last-child et_flex_column et_pb_css_mix_blend_mode_passthrough et_flex_column_24_24\">\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module\" href=\"\">BACK<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":72070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,47,50],"tags":[],"class_list":["post-72076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2-floor","category-apartments","category-two-room-apartment"],"_links":{"self":[{"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/posts\/72076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/comments?post=72076"}],"version-history":[{"count":1,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/posts\/72076\/revisions"}],"predecessor-version":[{"id":72077,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/posts\/72076\/revisions\/72077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/media\/72070"}],"wp:attachment":[{"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/media?parent=72076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/categories?post=72076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinoeoli.it\/en\/wp-json\/wp\/v2\/tags?post=72076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}